{"id":22392,"date":"2023-09-25T13:14:29","date_gmt":"2023-09-25T13:14:29","guid":{"rendered":"https:\/\/lluita.org\/?p=22392"},"modified":"2023-09-27T11:00:25","modified_gmt":"2023-09-27T11:00:25","slug":"celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento","status":"publish","type":"post","link":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/","title":{"rendered":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento"},"content":{"rendered":"<p><strong><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">VIH y envejecimiento<\/span><\/span> <\/span><\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Gracias a los avances en el tratamiento antirretroviral (TAR), las personas con infecci\u00f3n por el virus de la inmunodeficiencia humana (VIH) ahora pueden tener una esperanza de vida que se acerca m\u00e1s a la de la poblaci\u00f3n general (Blanco et al., 2017;<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Porter, 2003).<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Actualmente, estamos tratando la primera generaci\u00f3n de pacientes con infecci\u00f3n por VIH de edad avanzada, lo que implica que la informaci\u00f3n que se dispone sea limitada.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Sin embargo, debido al estado de inflamaci\u00f3n sist\u00e9mico cr\u00f3nico producido por la propia infecci\u00f3n por el VIH junto con las toxicidades de ciertos antirretrovirales, sabemos que las comorbilidades asociadas a este estado tienen una mayor prevalencia y pueden aparecer antes, por tanto,<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">hablamos de un envejecimiento m\u00e1s acentuado y acelerado.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Como en otras enfermedades cr\u00f3nicas, el manejo de estas personas es complejo y se necesita una atenci\u00f3n integral con un enfoque multidisciplinar, en el que se consideren las particularidades propias de este colectivo y que est\u00e9 orientado fundamentalmente a mejorar la calidad de vida de<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">estas personas.<\/span><\/span> <\/span><\/p>\n<p><strong><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Centro de Excelencia en VIH y Envejecimiento<\/span><\/span> <\/span><\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">La Fundaci\u00f3n Lucha contra las Infecciones, desde hace una d\u00e9cada, tiene una consolidada <a href=\"https:\/\/lluita.org\/es\/infeccions\/vih\/?swcfpc=1\">l\u00ednea de investigaci\u00f3n<\/a>, liderada por la <strong>Dra.<\/strong><\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"><strong>Eugenia Negredo<\/strong>, enfocada a estudiar el envejecimiento en pacientes VIH.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Los proyectos llevados a cabo, los hallazgos realizados en esta materia y los art\u00edculos publicados han tenido una gran repercusi\u00f3n nacional e internacional, posicionando al grupo como referente en la materia.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Este a\u00f1o el equipo y la entidad, han sido reconocidos como especialistas en la investigaci\u00f3n, el tratamiento y la atenci\u00f3n de personas infectadas con el VIH, recibiendo la acreditaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento, por el<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">programa de <a href=\"https:\/\/www.gilead.com\/\">Gilead Science<\/a>.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El reconocimiento como Centro de Excelencia en VIH y Envejecimiento posiciona al equipo y la entidad como centro formativo de referencia, con un papel crucial en la lucha contra el VIH y el sida, ya que ayudamos a mejorar la<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">calidad de vida de las personas infectadas, promoviendo la prevenci\u00f3n de la transmisi\u00f3n del VIH y contribuyendo al progreso de la investigaci\u00f3n y el desarrollo de tratamientos m\u00e1s efectivos.<\/span><\/span> <\/span><\/p>\n<p><strong><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento<\/span><\/span> <\/span><\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Estos d\u00edas en la Fundaci\u00f3n Lucha contra las Infecciones se ha llevado a cabo una formaci\u00f3n presencial, te\u00f3rica y, sobre todo, pr\u00e1ctica, sobre aspectos b\u00e1sicos y cl\u00ednicos del envejecimiento en la infecci\u00f3n por VIH con m\u00e1s de 12 horas lectivas repartidas en 2 d\u00edas<\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">La formaci\u00f3n muy personalizada estaba dirigida a un grupo muy reducido de profesionales m\u00e9dicos e investigadores con especial inter\u00e9s por la poblaci\u00f3n envejecida con infecci\u00f3n por VIH de todo el Estado espa\u00f1ol.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Ha incluido el abordaje de casos cl\u00ednicos, as\u00ed como la participaci\u00f3n de diferentes pacientes que han podido exponer su experiencia en primera persona.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El curso se program\u00f3 con el prop\u00f3sito de poner al paciente en el centro de todas las intervenciones para garantizarle un envejecimiento saludable y una mejor calidad de vida.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">As\u00ed pues, la formaci\u00f3n ha abordado no s\u00f3lo aspectos estrictamente m\u00e9dicos, sino tambi\u00e9n sociales, psicosociales, funcionales, cognitivos y geri\u00e1tricos.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Este taller ha sido coordinado cient\u00edficamente por la <strong>Dra.<\/strong><\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"><strong>Eugenia Negredo<\/strong>, jefe de secci\u00f3n VIH del <a href=\"https:\/\/www.hospitalgermanstrias.cat\/web\/guest\/inicio\">Hospital Universitario Germans Trias i Pujol<\/a>, y de la Fundaci\u00f3n Lucha contra las Infecciones, y ha contado con la participaci\u00f3n de expertos de su equipo y colaboradores habituales.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIH y envejecimiento Gracias a los avances en el tratamiento antirretroviral (TAR), las personas con infecci\u00f3n por el virus de la inmunodeficiencia humana (VIH) ahora pueden tener una esperanza de vida que se acerca m\u00e1s a la de la poblaci\u00f3n general (Blanco et al., 2017; Porter, 2003). Actualmente, estamos tratando la primera generaci\u00f3n de pacientes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"class_list":["post-22392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vih-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento - Fundaci\u00f3 Lluita contra les Infeccions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento\" \/>\n<meta property=\"og:description\" content=\"VIH y envejecimiento Gracias a los avances en el tratamiento antirretroviral (TAR), las personas con infecci\u00f3n por el virus de la inmunodeficiencia humana (VIH) ahora pueden tener una esperanza de vida que se acerca m\u00e1s a la de la poblaci\u00f3n general (Blanco et al., 2017; Porter, 2003). Actualmente, estamos tratando la primera generaci\u00f3n de pacientes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Lluita contra les Infeccions\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-25T13:14:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T11:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1-1024x512.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marta Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/\"},\"author\":{\"name\":\"Marta Rodriguez\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"headline\":\"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento\",\"datePublished\":\"2023-09-25T13:14:29+00:00\",\"dateModified\":\"2023-09-27T11:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/\"},\"wordCount\":620,\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/09\\\/Post_lk-tw_centroexcelencia-1.png\",\"articleSection\":[\"VIH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/\",\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/\",\"name\":\"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento - Fundaci\u00f3 Lluita contra les Infeccions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/09\\\/Post_lk-tw_centroexcelencia-1.png\",\"datePublished\":\"2023-09-25T13:14:29+00:00\",\"dateModified\":\"2023-09-27T11:00:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/09\\\/Post_lk-tw_centroexcelencia-1.png\",\"contentUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/09\\\/Post_lk-tw_centroexcelencia-1.png\",\"width\":4096,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lluita.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\",\"url\":\"https:\\\/\\\/lluita.org\\\/\",\"name\":\"Fundaci\u00f3 Lluita contra les Infeccions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lluita.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\",\"name\":\"Marta Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"caption\":\"Marta Rodriguez\"},\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/author\\\/mrodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento - Fundaci\u00f3 Lluita contra les Infeccions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento","og_description":"VIH y envejecimiento Gracias a los avances en el tratamiento antirretroviral (TAR), las personas con infecci\u00f3n por el virus de la inmunodeficiencia humana (VIH) ahora pueden tener una esperanza de vida que se acerca m\u00e1s a la de la poblaci\u00f3n general (Blanco et al., 2017; Porter, 2003). Actualmente, estamos tratando la primera generaci\u00f3n de pacientes [&hellip;]","og_url":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/","og_site_name":"Fundaci\u00f3 Lluita contra les Infeccions","article_published_time":"2023-09-25T13:14:29+00:00","article_modified_time":"2023-09-27T11:00:25+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1-1024x512.png","type":"image\/png"}],"author":"Marta Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Rodriguez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#article","isPartOf":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/"},"author":{"name":"Marta Rodriguez","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"headline":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento","datePublished":"2023-09-25T13:14:29+00:00","dateModified":"2023-09-27T11:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/"},"wordCount":620,"image":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1.png","articleSection":["VIH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/","url":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/","name":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento - Fundaci\u00f3 Lluita contra les Infeccions","isPartOf":{"@id":"https:\/\/lluita.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#primaryimage"},"image":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1.png","datePublished":"2023-09-25T13:14:29+00:00","dateModified":"2023-09-27T11:00:25+00:00","author":{"@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"breadcrumb":{"@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#primaryimage","url":"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1.png","contentUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/09\/Post_lk-tw_centroexcelencia-1.png","width":4096,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/lluita.org\/es\/celebramos-la-primera-jornada-de-formacion-como-centro-de-excelencia-en-vih-y-envejecimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lluita.org\/es\/"},{"@type":"ListItem","position":2,"name":"Celebramos la Primera Jornada de Formaci\u00f3n como Centro de Excelencia en VIH y Envejecimiento"}]},{"@type":"WebSite","@id":"https:\/\/lluita.org\/#website","url":"https:\/\/lluita.org\/","name":"Fundaci\u00f3 Lluita contra les Infeccions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluita.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced","name":"Marta Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","caption":"Marta Rodriguez"},"url":"https:\/\/lluita.org\/es\/author\/mrodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/comments?post=22392"}],"version-history":[{"count":4,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22392\/revisions"}],"predecessor-version":[{"id":22399,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22392\/revisions\/22399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media\/22393"}],"wp:attachment":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media?parent=22392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/categories?post=22392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}