{"id":22738,"date":"2023-11-13T09:46:32","date_gmt":"2023-11-13T09:46:32","guid":{"rendered":"https:\/\/lluita.org\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/"},"modified":"2024-04-02T13:48:10","modified_gmt":"2024-04-02T13:48:10","slug":"la-roba-que-ja-no-utilitzes-pot-salvar-vides","status":"publish","type":"post","link":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/","title":{"rendered":"La ropa que ya no utilizas puede salvar vidas"},"content":{"rendered":"<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">La pandemia de la Covid-19 nos recuerda que las infecciones son un riesgo inevitable al que todos estamos expuestos y que la \u00fanica forma de combatirlo es gracias a la investigaci\u00f3n<\/span><\/span><\/span>.<\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><strong><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00bfQuieres formar parte de nuestra lucha?<\/span><\/span><\/strong> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Desde la Fundaci\u00f3n Lucha contra las Infecciones estamos impulsando un armario de ropa solidario.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">La forma de colaborar es ofreciendo la ropa que ya no utilizas o comprando ropa de segunda mano de nuestro armario solidario.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Esta campa\u00f1a da una segunda oportunidad a la ropa que ya no se utiliza y, al mismo tiempo, ofrece un impulso a nuestra investigaci\u00f3n, ya que el dinero que se recoge de las prendas vendidas, mediante la plataforma de micolet, se destina \u00edntegramente<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">a financiar proyectos de investigaci\u00f3n para tratar y curar a las personas que padecen una enfermedad infecciosa<\/span><\/span><\/span>.<\/p>\n<p><strong><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00bfQuieres comprar ropa solidaria?<\/span><\/span><\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.micolet.com\/armario\/fundaciolluita\">Si quieres comprar una prenda de ropa de nuestro armario solidario clica el enlace<\/a>.<\/p>\n<p><strong>\u00bfQuieres dar tu ropa?<\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Es necesario que sigas estos pasos:<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">1. Selecciona un m\u00ednimo de 20 prendas que ya no utilices (deben estar limpias y en buenas condiciones).<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2. Es necesario que rellenes <a href=\"https:\/\/www.recogidasmicolet.com\/lluita\/\">este formulario<\/a> y el mensajero de micolet te recoger\u00e1 las piezas en la direcci\u00f3n postal que indiques.<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">3. Un mensajero de micolet recoger\u00e1 tus cajas tan pronto como pueda.<\/span><\/span><\/span><\/p>\n<p>4. <span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Toda la ropa recogida en buen estado se pondr\u00e1 a la venta en<\/span><\/span><\/span> <a href=\"https:\/\/www.micolet.com\/\">www.micolet.com<\/a><\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El 100% de los beneficios obtenidos de la campa\u00f1a se destinar\u00e1n a favor de la Fundaci\u00f3n Lucha contra las Infecciones<\/span><\/span><\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"HwtZe\" lang=\"es\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00a1El futuro es incierto y la lucha contin\u00faa!<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia de la Covid-19 nos recuerda que las infecciones son un riesgo inevitable al que todos estamos expuestos y que la \u00fanica forma de combatirlo es gracias a la investigaci\u00f3n. \u00bfQuieres formar parte de nuestra lucha? Desde la Fundaci\u00f3n Lucha contra las Infecciones estamos impulsando un armario de ropa solidario. La forma de colaborar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,19,20,268,269,270],"class_list":["post-22738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19-es","category-vih-es","category-its-es","category-infecciones-bacaterianas-graves","category-infecciones-en-pacientes-inmunodeprimidos","category-salud-internacional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La ropa que ya no utilizas puede salvar vidas - Fundaci\u00f3 Lluita contra les Infeccions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ropa que ya no utilizas puede salvar vidas\" \/>\n<meta property=\"og:description\" content=\"La pandemia de la Covid-19 nos recuerda que las infecciones son un riesgo inevitable al que todos estamos expuestos y que la \u00fanica forma de combatirlo es gracias a la investigaci\u00f3n. \u00bfQuieres formar parte de nuestra lucha? Desde la Fundaci\u00f3n Lucha contra las Infecciones estamos impulsando un armario de ropa solidario. La forma de colaborar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Lluita contra les Infeccions\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T09:46:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T13:48:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet-1024x484.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marta Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/\"},\"author\":{\"name\":\"Marta Rodriguez\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"headline\":\"La ropa que ya no utilizas puede salvar vidas\",\"datePublished\":\"2023-11-13T09:46:32+00:00\",\"dateModified\":\"2024-04-02T13:48:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/\"},\"wordCount\":273,\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/11\\\/Img_bloc_micolet.png\",\"articleSection\":[\"COVID-19\",\"VIH\",\"ITS\",\"Infecciones bacterianas graves\",\"Infecciones en pacientes inmunodeprimidos\",\"Salud internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/\",\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/\",\"name\":\"La ropa que ya no utilizas puede salvar vidas - Fundaci\u00f3 Lluita contra les Infeccions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/11\\\/Img_bloc_micolet.png\",\"datePublished\":\"2023-11-13T09:46:32+00:00\",\"dateModified\":\"2024-04-02T13:48:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/11\\\/Img_bloc_micolet.png\",\"contentUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2023\\\/11\\\/Img_bloc_micolet.png\",\"width\":1800,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lluita.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ropa que ya no utilizas puede salvar vidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\",\"url\":\"https:\\\/\\\/lluita.org\\\/\",\"name\":\"Fundaci\u00f3 Lluita contra les Infeccions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lluita.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\",\"name\":\"Marta Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"caption\":\"Marta Rodriguez\"},\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/author\\\/mrodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La ropa que ya no utilizas puede salvar vidas - Fundaci\u00f3 Lluita contra les Infeccions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/","og_locale":"es_ES","og_type":"article","og_title":"La ropa que ya no utilizas puede salvar vidas","og_description":"La pandemia de la Covid-19 nos recuerda que las infecciones son un riesgo inevitable al que todos estamos expuestos y que la \u00fanica forma de combatirlo es gracias a la investigaci\u00f3n. \u00bfQuieres formar parte de nuestra lucha? Desde la Fundaci\u00f3n Lucha contra las Infecciones estamos impulsando un armario de ropa solidario. La forma de colaborar [&hellip;]","og_url":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/","og_site_name":"Fundaci\u00f3 Lluita contra les Infeccions","article_published_time":"2023-11-13T09:46:32+00:00","article_modified_time":"2024-04-02T13:48:10+00:00","og_image":[{"width":1024,"height":484,"url":"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet-1024x484.png","type":"image\/png"}],"author":"Marta Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#article","isPartOf":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/"},"author":{"name":"Marta Rodriguez","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"headline":"La ropa que ya no utilizas puede salvar vidas","datePublished":"2023-11-13T09:46:32+00:00","dateModified":"2024-04-02T13:48:10+00:00","mainEntityOfPage":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/"},"wordCount":273,"image":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet.png","articleSection":["COVID-19","VIH","ITS","Infecciones bacterianas graves","Infecciones en pacientes inmunodeprimidos","Salud internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/","url":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/","name":"La ropa que ya no utilizas puede salvar vidas - Fundaci\u00f3 Lluita contra les Infeccions","isPartOf":{"@id":"https:\/\/lluita.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#primaryimage"},"image":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet.png","datePublished":"2023-11-13T09:46:32+00:00","dateModified":"2024-04-02T13:48:10+00:00","author":{"@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"breadcrumb":{"@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#primaryimage","url":"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet.png","contentUrl":"https:\/\/lluita.org\/custom\/uploads\/2023\/11\/Img_bloc_micolet.png","width":1800,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/lluita.org\/es\/la-roba-que-ja-no-utilitzes-pot-salvar-vides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lluita.org\/es\/"},{"@type":"ListItem","position":2,"name":"La ropa que ya no utilizas puede salvar vidas"}]},{"@type":"WebSite","@id":"https:\/\/lluita.org\/#website","url":"https:\/\/lluita.org\/","name":"Fundaci\u00f3 Lluita contra les Infeccions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluita.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced","name":"Marta Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","caption":"Marta Rodriguez"},"url":"https:\/\/lluita.org\/es\/author\/mrodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/comments?post=22738"}],"version-history":[{"count":5,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22738\/revisions"}],"predecessor-version":[{"id":23305,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/22738\/revisions\/23305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media\/22734"}],"wp:attachment":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media?parent=22738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/categories?post=22738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}