{"id":23072,"date":"2024-01-30T15:44:41","date_gmt":"2024-01-30T15:44:41","guid":{"rendered":"https:\/\/lluita.org\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/"},"modified":"2024-01-31T09:23:03","modified_gmt":"2024-01-31T09:23:03","slug":"sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals","status":"publish","type":"post","link":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/","title":{"rendered":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?"},"content":{"rendered":"<p>El pasado 10 de enero, el Congreso de los Diputados convalid\u00f3 el Real Decreto Ley 6\/2023 que modifica la <a href=\"https:\/\/www.boe.es\/eli\/es\/rdl\/2023\/12\/19\/6\/con\">Ley 49\/2002, de 23 de diciembre<\/a>, de r\u00e9gimen fiscal de las entidades sin fines lucrativos y de los incentivos fiscales en el mecenazgo.<\/p>\n<p>Con esta convalidaci\u00f3n, la reforma de la Ley del mecenazgo pasa a ser definitiva y las novedades fiscales se aplicar\u00e1n a las donaciones realizadas o recibidas desde el 1 de enero, que se declarar\u00e1n y deducir\u00e1n en 2025.<\/p>\n<p>La reforma de la Ley del mecenazgo es una buena noticia para todas las entidades sin \u00e1nimo de lucro que trabajemos para generar impacto positivo en la sociedad. Los incentivos fiscales permitir\u00e1n que m\u00e1s personas y empresas decidan ser solidarias y que las que ya lo son puedan incrementar sus cuotas sin que repercuta excesivamente en su econom\u00eda.<\/p>\n<p><strong>\u00bfC\u00f3mo me afecta esto si ya soy donante o quiero serlo?<\/strong><\/p>\n<p>En el caso de las personas f\u00edsicas, se eleva la base sobre la que se puede deducir el 80% de la donaci\u00f3n en el IRPF. Si hasta ahora eran 150\u20ac, ahora pasan a ser 250\u20ac. Esto significa que <strong>los primeros 250\u20ac de tu donaci\u00f3n desgravan el 80%.<\/strong><\/p>\n<p><strong>El resto de la cantidad<\/strong> (m\u00e1s all\u00e1 de los 250 \u20ac) <strong>tiene ahora una deducci\u00f3n del 40%<\/strong>, en lugar del 35%. Adem\u00e1s, si en los <strong>\u00faltimos 3 a\u00f1os<\/strong> se han realizado donaciones a favor de la propia entidad, si el importe es igual o superior al del ejercicio anterior, el porcentaje de deducci\u00f3n aplicable <strong>asciende al 45%<\/strong>.<\/p>\n<p><strong>\u00bfY si soy una empresa?<\/strong><\/p>\n<p>En el caso de las personas jur\u00eddicas, se incrementa el porcentaje de deducci\u00f3n en la cuota del Impuesto sobre Sociedades, pasando del 35% al <strong>40%<\/strong>. Adem\u00e1s, si en los <strong>\u00faltimos 3 a\u00f1os<\/strong> se han realizado donaciones a la misma entidad de igual o superior valor al ejercicio anterior, el porcentaje de deducci\u00f3n <strong>se incrementa hasta el 50%<\/strong>.<\/p>\n<p>Cabe destacar que la base de deducci\u00f3n tanto de personas f\u00edsicas como jur\u00eddicas no puede superar el 15% de la base imponible del per\u00edodo impositivo, 5 puntos m\u00e1s que hasta ahora.<\/p>\n<p><strong>Otras formas de colaborar<\/strong><\/p>\n<p>A partir de ahora, la <strong>cesi\u00f3n de un bien mueble o inmueble<\/strong>, por tiempo determinado, realizada sin contraprestaci\u00f3n, puede generar <strong>derecho a deducci\u00f3n<\/strong>.<\/p>\n<p>Tambi\u00e9n se a\u00f1aden las <strong>prestaciones de servicios como medio de colaboraci\u00f3n<\/strong> con las entidades beneficiarias del mecenazgo. Se especifica que puede ser una ayuda econ\u00f3mica, pero tambi\u00e9n se permite que sea en especie oa trav\u00e9s de la prestaci\u00f3n de servicios realizados en el \u00e1mbito de la actividad econ\u00f3mica propia del colaborador (hasta ahora s\u00f3lo pod\u00eda ser donativo econ\u00f3mico).<\/p>\n<p>Tambi\u00e9n se ampl\u00eda el concepto de <strong>difusi\u00f3n de la colaboraci\u00f3n<\/strong>, ya que adem\u00e1s de realizarla la ONG, ahora tambi\u00e9n puede realizarla el colaborador. Uno de los objetivos de la reforma de la ley es precisamente poder difundir los esfuerzos privados en actividades de inter\u00e9s general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 10 de enero, el Congreso de los Diputados convalid\u00f3 el Real Decreto Ley 6\/2023 que modifica la Ley 49\/2002, de 23 de diciembre, de r\u00e9gimen fiscal de las entidades sin fines lucrativos y de los incentivos fiscales en el mecenazgo. Con esta convalidaci\u00f3n, la reforma de la Ley del mecenazgo pasa a ser [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,19,20,125,267,268,269,270],"class_list":["post-23072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19-es","category-vih-es","category-its-es","category-solidaridad","category-bonaventura-clotet-es","category-infecciones-bacaterianas-graves","category-infecciones-en-pacientes-inmunodeprimidos","category-salud-internacional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales? - Fundaci\u00f3 Lluita contra les Infeccions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?\" \/>\n<meta property=\"og:description\" content=\"El pasado 10 de enero, el Congreso de los Diputados convalid\u00f3 el Real Decreto Ley 6\/2023 que modifica la Ley 49\/2002, de 23 de diciembre, de r\u00e9gimen fiscal de las entidades sin fines lucrativos y de los incentivos fiscales en el mecenazgo. Con esta convalidaci\u00f3n, la reforma de la Ley del mecenazgo pasa a ser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Lluita contra les Infeccions\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T15:44:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T09:23:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/\"},\"author\":{\"name\":\"Marta Rodriguez\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"headline\":\"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?\",\"datePublished\":\"2024-01-30T15:44:41+00:00\",\"dateModified\":\"2024-01-31T09:23:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/\"},\"wordCount\":517,\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2024\\\/01\\\/llei_mecenatge.jpg\",\"articleSection\":[\"COVID-19\",\"VIH\",\"ITS\",\"Solidaridad\",\"Bonaventura Clotet\",\"Infecciones bacterianas graves\",\"Infecciones en pacientes inmunodeprimidos\",\"Salud internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/\",\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/\",\"name\":\"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales? - Fundaci\u00f3 Lluita contra les Infeccions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2024\\\/01\\\/llei_mecenatge.jpg\",\"datePublished\":\"2024-01-30T15:44:41+00:00\",\"dateModified\":\"2024-01-31T09:23:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2024\\\/01\\\/llei_mecenatge.jpg\",\"contentUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2024\\\/01\\\/llei_mecenatge.jpg\",\"width\":1800,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lluita.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\",\"url\":\"https:\\\/\\\/lluita.org\\\/\",\"name\":\"Fundaci\u00f3 Lluita contra les Infeccions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lluita.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/33335fd0597aa3cc324e8b520d25eced\",\"name\":\"Marta Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g\",\"caption\":\"Marta Rodriguez\"},\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/author\\\/mrodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales? - Fundaci\u00f3 Lluita contra les Infeccions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?","og_description":"El pasado 10 de enero, el Congreso de los Diputados convalid\u00f3 el Real Decreto Ley 6\/2023 que modifica la Ley 49\/2002, de 23 de diciembre, de r\u00e9gimen fiscal de las entidades sin fines lucrativos y de los incentivos fiscales en el mecenazgo. Con esta convalidaci\u00f3n, la reforma de la Ley del mecenazgo pasa a ser [&hellip;]","og_url":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/","og_site_name":"Fundaci\u00f3 Lluita contra les Infeccions","article_published_time":"2024-01-30T15:44:41+00:00","article_modified_time":"2024-01-31T09:23:03+00:00","og_image":[{"width":1800,"height":850,"url":"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg","type":"image\/jpeg"}],"author":"Marta Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Rodriguez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#article","isPartOf":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/"},"author":{"name":"Marta Rodriguez","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"headline":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?","datePublished":"2024-01-30T15:44:41+00:00","dateModified":"2024-01-31T09:23:03+00:00","mainEntityOfPage":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/"},"wordCount":517,"image":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg","articleSection":["COVID-19","VIH","ITS","Solidaridad","Bonaventura Clotet","Infecciones bacterianas graves","Infecciones en pacientes inmunodeprimidos","Salud internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/","url":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/","name":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales? - Fundaci\u00f3 Lluita contra les Infeccions","isPartOf":{"@id":"https:\/\/lluita.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#primaryimage"},"image":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg","datePublished":"2024-01-30T15:44:41+00:00","dateModified":"2024-01-31T09:23:03+00:00","author":{"@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced"},"breadcrumb":{"@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#primaryimage","url":"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg","contentUrl":"https:\/\/lluita.org\/custom\/uploads\/2024\/01\/llei_mecenatge.jpg","width":1800,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/lluita.org\/es\/sabies-que-donar-a-entitats-sense-anim-de-lucre-ara-te-mes-avantatges-fiscals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lluita.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfSab\u00edas que dar a entidades sin \u00e1nimo de lucro tiene ahora m\u00e1s ventajas fiscales?"}]},{"@type":"WebSite","@id":"https:\/\/lluita.org\/#website","url":"https:\/\/lluita.org\/","name":"Fundaci\u00f3 Lluita contra les Infeccions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluita.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lluita.org\/#\/schema\/person\/33335fd0597aa3cc324e8b520d25eced","name":"Marta Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6b119cbae43b329ad19d1889130bcf7e6567ba0ec896ae9cb1848863b6dabdd?s=96&d=mm&r=g","caption":"Marta Rodriguez"},"url":"https:\/\/lluita.org\/es\/author\/mrodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/23072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/comments?post=23072"}],"version-history":[{"count":6,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/23072\/revisions"}],"predecessor-version":[{"id":23082,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/23072\/revisions\/23082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media\/23070"}],"wp:attachment":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media?parent=23072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/categories?post=23072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}