{"id":24771,"date":"2025-04-28T15:31:14","date_gmt":"2025-04-28T13:31:14","guid":{"rendered":"https:\/\/lluita.org\/mes-de-120-persones-han-col%c2%b7laborat-amb-la-nostra-iniciativa-de-sant-jordi\/"},"modified":"2025-04-30T09:55:32","modified_gmt":"2025-04-30T07:55:32","slug":"mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi","status":"publish","type":"post","link":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/","title":{"rendered":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi"},"content":{"rendered":"<p><span data-contrast=\"auto\">Este a\u00f1o, por Sant Jordi, en la <\/span><a href=\"https:\/\/lluita.org\/es\/\"><span data-contrast=\"none\">Fundaci\u00f3n Lucha contra las Infecciones<\/span><\/a><span data-contrast=\"auto\"> hemos vuelto a poner la <strong>solidaridad y la investigaci\u00f3n en el centro.<\/strong> Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para <a href=\"https:\/\/www.20minutos.es\/noticia\/5700641\/0\/limpieza-plasma-para-tratar-covid-persistente-es-ineficaz-segun-un-ensayo-clinico-hospital-can-ruti-badalona\/\"><strong>recordar la importancia de la investigaci\u00f3n en COVID persistente<\/strong>.<\/a><\/span><\/p>\n<p><span data-contrast=\"auto\">Para hacerlo, iniciamos una campa\u00f1a para colaborar en la investigaci\u00f3n de esta enfermedad, la cual <strong>afecta a un 10% de las personas que han sufrido la <a href=\"https:\/\/lluita.org\/es\/infeccions\/covid-19\/\">COVID-19<\/a><\/strong> y que les dificulta llevar una vida normal.\u00a0\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">M\u00e1s de 120 personas han colaborado en nuestra campa\u00f1a <\/span><\/b>para la investigaci\u00f3n en la COVID persistente, lo que demuestra una vez m\u00e1s la solidaridad y el compromiso de las personas con la lucha contra las enfermedades infecciosas.<\/p>\n<p>Por otro lado, en la Fundaci\u00f3n, celebramos Sant Jordi con un <strong>intercambio de libros<\/strong> y con el <strong>regalo de una rosa<\/strong>. Una actividad para fomentar la lectura y la solidaridad entre los compa\u00f1eros y compa\u00f1eras.<\/p>\n<h3>\u00a1Gracias a todas las personas que os hab\u00e9is sumado al proyecto!<\/h3>\n<p><span data-contrast=\"auto\">Acciones como esta permiten avanzar en la investigaci\u00f3n y estar m\u00e1s cerca de encontrar un tratamiento. Para la Fundaci\u00f3n, esto es una prioridad y hemos dado pasos muy importantes en el diagn\u00f3stico y tratamiento de la enfermedad.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o, por Sant Jordi, en la Fundaci\u00f3n Lucha contra las Infecciones hemos vuelto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente. Para hacerlo, iniciamos una campa\u00f1a para colaborar en la investigaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":24767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,125],"class_list":["post-24771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19-es","category-solidaridad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi - Fundaci\u00f3 Lluita contra les Infeccions<\/title>\n<meta name=\"description\" content=\"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi\" \/>\n<meta property=\"og:description\" content=\"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Lluita contra les Infeccions\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T13:31:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T07:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LLUITA Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LLUITA Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/\"},\"author\":{\"name\":\"LLUITA Admin\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\"},\"headline\":\"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi\",\"datePublished\":\"2025-04-28T13:31:14+00:00\",\"dateModified\":\"2025-04-30T07:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/\"},\"wordCount\":228,\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/04\\\/IMG_2764-scaled.jpeg\",\"articleSection\":[\"COVID-19\",\"Solidaridad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/\",\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/\",\"name\":\"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi - Fundaci\u00f3 Lluita contra les Infeccions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/04\\\/IMG_2764-scaled.jpeg\",\"datePublished\":\"2025-04-28T13:31:14+00:00\",\"dateModified\":\"2025-04-30T07:55:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\"},\"description\":\"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/04\\\/IMG_2764-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/04\\\/IMG_2764-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Campanya Sant Jordi covid persistent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lluita.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\",\"url\":\"https:\\\/\\\/lluita.org\\\/\",\"name\":\"Fundaci\u00f3 Lluita contra les Infeccions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lluita.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\",\"name\":\"LLUITA Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"caption\":\"LLUITA Admin\"},\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/author\\\/lluita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi - Fundaci\u00f3 Lluita contra les Infeccions","description":"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi","og_description":"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.","og_url":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/","og_site_name":"Fundaci\u00f3 Lluita contra les Infeccions","article_published_time":"2025-04-28T13:31:14+00:00","article_modified_time":"2025-04-30T07:55:32+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg","type":"image\/jpeg"}],"author":"LLUITA Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LLUITA Admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#article","isPartOf":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/"},"author":{"name":"LLUITA Admin","@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a"},"headline":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi","datePublished":"2025-04-28T13:31:14+00:00","dateModified":"2025-04-30T07:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/"},"wordCount":228,"image":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg","articleSection":["COVID-19","Solidaridad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/","url":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/","name":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi - Fundaci\u00f3 Lluita contra les Infeccions","isPartOf":{"@id":"https:\/\/lluita.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#primaryimage"},"image":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg","datePublished":"2025-04-28T13:31:14+00:00","dateModified":"2025-04-30T07:55:32+00:00","author":{"@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a"},"description":"Por Sant Jordi, hemos vulto a poner la solidaridad y la investigaci\u00f3n en el centro. Por eso, por segundo a\u00f1o consecutivo, hemos aprovechado esta fecha para recordar la importancia de la investigaci\u00f3n en COVID persistente.","breadcrumb":{"@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#primaryimage","url":"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg","contentUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/04\/IMG_2764-scaled.jpeg","width":2560,"height":1920,"caption":"Campanya Sant Jordi covid persistent"},{"@type":"BreadcrumbList","@id":"https:\/\/lluita.org\/es\/mas-de-120-personas-han-colaborado-en-la-campanya-de-sant-jordi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lluita.org\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 120 personas han colaborado en nuestra iniciativa de Sant Jordi"}]},{"@type":"WebSite","@id":"https:\/\/lluita.org\/#website","url":"https:\/\/lluita.org\/","name":"Fundaci\u00f3 Lluita contra les Infeccions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluita.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a","name":"LLUITA Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","caption":"LLUITA Admin"},"url":"https:\/\/lluita.org\/es\/author\/lluita\/"}]}},"_links":{"self":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/24771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/comments?post=24771"}],"version-history":[{"count":7,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/24771\/revisions"}],"predecessor-version":[{"id":24783,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/24771\/revisions\/24783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media\/24767"}],"wp:attachment":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media?parent=24771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/categories?post=24771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}