{"id":25368,"date":"2025-10-06T10:14:23","date_gmt":"2025-10-06T08:14:23","guid":{"rendered":"https:\/\/lluita.org\/?p=25368"},"modified":"2025-10-06T10:14:23","modified_gmt":"2025-10-06T08:14:23","slug":"el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura","status":"publish","type":"post","link":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/","title":{"rendered":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.mdpi.com\/2076-393X\/13\/6\/594\">estudio<\/a> internacional \u2018REMAIN\u2019, dedicado a evaluar la eficacia y la seguridad de <strong>la vacuna MVA-BN contra la mpox<\/strong> en poblaciones con alto riesgo de infecci\u00f3n, confirma que esta <strong>es segura<\/strong>. La investigaci\u00f3n ha sido liderada por las investigadoras <strong>Roser Escrig-Sarreta, Clara Su\u00f1er y Cristina Galv\u00e1n-Casas<\/strong>, del equipo del <strong>Dr. Oriol Mitj\u00e0<\/strong>, jefe de la l\u00ednea de Infecciones de Transmisi\u00f3n Sexual de la <a href=\"https:\/\/lluita.org\/es\/\">Fundaci\u00f3n Lucha contra las Infecciones<\/a> y del Hospital Germans Trias i Pujol. Este es el <strong>primer gran proyecto internacional<\/strong> que reproduce las condiciones de un ensayo cl\u00ednico y que <strong>aporta evidencia cient\u00edfica sobre la eficacia y la seguridad de la vacuna en condiciones reales.<\/strong><\/p>\n<p>La investigaci\u00f3n se ha desarrollado entre 2022 y 2024 y ha contado con <strong>la participaci\u00f3n de 4.600 personas de Espa\u00f1a, Panam\u00e1, Per\u00fa y Chile<\/strong>, en su mayor\u00eda hombres con factores de riesgo para contraer la mpox. En este <strong>estudio observacional<\/strong>, la vacuna, la m\u00e1s utilizada para controlar la enfermedad, ha sido administrada por los sistemas de salud locales, mientras que el equipo investigador ha recogido los datos mediante encuestas y ha realizado un seguimiento cl\u00ednico. Los resultados, publicados en la revista cient\u00edfica <em>Vaccines<\/em>, confirman el valor preventivo de la MVA-BN.<\/p>\n<h3>\u00bfC\u00f3mo se ha desarrollado el estudio de la vacuna <b><span data-contrast=\"none\">MVA-BN<\/span><\/b>?<\/h3>\n<p>De los casi 5.000 participantes, aproximadamente <strong>1.000 fueron seleccionados para analizar la eficacia de la vacuna<\/strong> y se agruparon en 500 parejas de personas vacunadas y no vacunadas con caracter\u00edsticas similares, como edad, factores de riesgo para contraer la mpox o lugar de residencia. Cabe destacar que esta estrategia de emparejamiento permite simular las condiciones de un ensayo cl\u00ednico y atribuir con mayor precisi\u00f3n los efectos observados a la vacuna.<\/p>\n<p>Durante el periodo del estudio,<strong> se observ\u00f3 una reducci\u00f3n global dr\u00e1stica de la incidencia de la mpox<\/strong>, con solo 8 casos registrados entre las parejas analizadas. Aunque se detectaron menos contagios en el grupo de personas vacunadas (0,6%) que en el de no vacunadas (1%), el n\u00famero tan bajo de casos impide atribuir esta diferencia de forma concluyente a la vacuna.<\/p>\n<p>A pesar de ello, <strong>el estudio refuerza el valor preventivo de la MVA-BN<\/strong>, que ya se hab\u00eda empezado a utilizar en 2022 en respuesta a la emergencia sanitaria global, ante la ausencia de alternativas terap\u00e9uticas contrastadas. Esta investigaci\u00f3n refuerza el conocimiento general aportado por otros estudios, que tambi\u00e9n se\u00f1alan su eficacia.<\/p>\n<p>Por otro lado, para evaluar la <strong>seguridad<\/strong>, se analizaron los datos de 1.500 participantes que hab\u00edan recibido la vacuna y dispon\u00edan de seguimiento con informaci\u00f3n sobre posibles efectos adversos. Estos han sido leves, como enrojecimiento, picor o inflamaci\u00f3n en el lugar de la inyecci\u00f3n. Adem\u00e1s, un <strong>25% de los participantes presentaron una marca visible en la zona de la inyecci\u00f3n<\/strong> <strong>que perdur\u00f3 m\u00e1s de seis meses<\/strong>, lo que sugiere la necesidad de revisar la localizaci\u00f3n de la administraci\u00f3n.<\/p>\n<h3>La colaboraci\u00f3n internacional, una herramienta clave para fomentar la investigaci\u00f3n de calidad<\/h3>\n<p>El estudio ha sido posible <strong>gracias al apoyo de centros de salud, puntos de vacunaci\u00f3n y organizaciones comunitarias de salud sexual de los cuatro pa\u00edses participantes,<\/strong> que han liderado el reclutamiento y el seguimiento de los voluntarios.<\/p>\n<p>Roser Escrig-Sarreta, coautora principal del estudio, destaca: <em>\u201cLa experiencia del estudio \u2018REMAIN\u2019 demuestra que <strong>la colaboraci\u00f3n cient\u00edfica internacional es esencial para dar una respuesta r\u00e1pida y efectiva a problemas urgentes de salud global<\/strong>. Solo sumando esfuerzos entre instituciones, profesionales de la salud y comunidades podemos generar conocimiento \u00fatil para proteger a las poblaciones m\u00e1s vulnerables.\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudio internacional \u2018REMAIN\u2019, dedicado a evaluar la eficacia y la seguridad de la vacuna MVA-BN contra la mpox en poblaciones con alto riesgo de infecci\u00f3n, confirma que esta es segura. La investigaci\u00f3n ha sido liderada por las investigadoras Roser Escrig-Sarreta, Clara Su\u00f1er y Cristina Galv\u00e1n-Casas, del equipo del Dr. Oriol Mitj\u00e0, jefe de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":25367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[270],"class_list":["post-25368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-internacional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura - Fundaci\u00f3 Lluita contra les Infeccions<\/title>\n<meta name=\"description\" content=\"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura\" \/>\n<meta property=\"og:description\" content=\"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Lluita contra les Infeccions\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-06T08:14:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LLUITA Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LLUITA Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/\"},\"author\":{\"name\":\"LLUITA Admin\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\"},\"headline\":\"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura\",\"datePublished\":\"2025-10-06T08:14:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/\"},\"wordCount\":626,\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/10\\\/Equip-Oriol-Mitja-4-scaled.jpg\",\"articleSection\":[\"Salud internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/\",\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/\",\"name\":\"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura - Fundaci\u00f3 Lluita contra les Infeccions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/10\\\/Equip-Oriol-Mitja-4-scaled.jpg\",\"datePublished\":\"2025-10-06T08:14:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\"},\"description\":\"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/10\\\/Equip-Oriol-Mitja-4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lluita.org\\\/custom\\\/uploads\\\/2025\\\/10\\\/Equip-Oriol-Mitja-4-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"vacuna MVA-BN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lluita.org\\\/es\\\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lluita.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#website\",\"url\":\"https:\\\/\\\/lluita.org\\\/\",\"name\":\"Fundaci\u00f3 Lluita contra les Infeccions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lluita.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lluita.org\\\/#\\\/schema\\\/person\\\/ebbfd4b21b6e55289e039158312b195a\",\"name\":\"LLUITA Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g\",\"caption\":\"LLUITA Admin\"},\"url\":\"https:\\\/\\\/lluita.org\\\/es\\\/author\\\/lluita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura - Fundaci\u00f3 Lluita contra les Infeccions","description":"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/","og_locale":"es_ES","og_type":"article","og_title":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura","og_description":"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.","og_url":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/","og_site_name":"Fundaci\u00f3 Lluita contra les Infeccions","article_published_time":"2025-10-06T08:14:23+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg","type":"image\/jpeg"}],"author":"LLUITA Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LLUITA Admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#article","isPartOf":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/"},"author":{"name":"LLUITA Admin","@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a"},"headline":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura","datePublished":"2025-10-06T08:14:23+00:00","mainEntityOfPage":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/"},"wordCount":626,"image":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg","articleSection":["Salud internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/","url":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/","name":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura - Fundaci\u00f3 Lluita contra les Infeccions","isPartOf":{"@id":"https:\/\/lluita.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#primaryimage"},"image":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#primaryimage"},"thumbnailUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg","datePublished":"2025-10-06T08:14:23+00:00","author":{"@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a"},"description":"Un nuevo estudio internacional confirma que la vacuna MVA-BN contra la mpox es segura y muestra efectos secundarios leves. Liderado por el Dr. Oriol Mitj\u00e0, el proyecto REMAIN aporta evidencia cient\u00edfica sobre su eficacia en poblaciones con alto riesgo de infecci\u00f3n.","breadcrumb":{"@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#primaryimage","url":"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg","contentUrl":"https:\/\/lluita.org\/custom\/uploads\/2025\/10\/Equip-Oriol-Mitja-4-scaled.jpg","width":2560,"height":1707,"caption":"vacuna MVA-BN"},{"@type":"BreadcrumbList","@id":"https:\/\/lluita.org\/es\/el-equipo-del-dr-oriol-mitja-presenta-un-nuevo-estudio-que-confirma-que-la-vacuna-mva-bn-contra-la-mpox-es-segura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lluita.org\/es\/"},{"@type":"ListItem","position":2,"name":"El equipo del Dr. Oriol Mitj\u00e0 presenta un nuevo estudio que confirma que la vacuna MVA-BN contra la mpox es segura"}]},{"@type":"WebSite","@id":"https:\/\/lluita.org\/#website","url":"https:\/\/lluita.org\/","name":"Fundaci\u00f3 Lluita contra les Infeccions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluita.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lluita.org\/#\/schema\/person\/ebbfd4b21b6e55289e039158312b195a","name":"LLUITA Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f51e89f2d1a045d315b4e165e3eb08f2b3fd6e86e5b4f0aa29788174420124f5?s=96&d=mm&r=g","caption":"LLUITA Admin"},"url":"https:\/\/lluita.org\/es\/author\/lluita\/"}]}},"_links":{"self":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/25368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/comments?post=25368"}],"version-history":[{"count":5,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/25368\/revisions"}],"predecessor-version":[{"id":25375,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/posts\/25368\/revisions\/25375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media\/25367"}],"wp:attachment":[{"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/media?parent=25368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lluita.org\/es\/wp-json\/wp\/v2\/categories?post=25368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}